{"id":2877,"date":"2024-06-04T12:31:47","date_gmt":"2024-06-04T16:31:47","guid":{"rendered":"https:\/\/tulibreando.com\/?post_type=product&#038;p=2877"},"modified":"2024-06-06T15:18:12","modified_gmt":"2024-06-06T19:18:12","slug":"rodeado-de-idiotas","status":"publish","type":"product","link":"https:\/\/tulibreando.com\/index.php\/product\/rodeado-de-idiotas\/","title":{"rendered":"Rodeado de idiotas"},"content":{"rendered":"<p>\u00bfAlguna vez te sientes incomprendido?<\/p>\n<p>\u00bfHas intentado razonar con alguien y hab\u00e9is acabado a gritos?<\/p>\n<p>\u00bfHas salido de una reuni\u00f3n pensando que est\u00e1s perdiendo el tiempo?<\/p>\n<p>O, lo que es peor, \u00bfla gente a veces no entiende lo que dices, por m\u00e1s claramente que lo expliques?<\/p>\n<p>No est\u00e1s solo. Tras una reuni\u00f3n desastrosa con un empresario de \u00e9xito que estaba convencido de estar \u00abrodeado de idiotas\u00bb, Thomas Erikson ide\u00f3 un revolucionario m\u00e9todo de clasificaci\u00f3n del comportamiento que divide a las personas en cuatro tipos:\u00a0<strong>los rojos, dominantes y ambiciosos<\/strong>;\u00a0<strong>los amarillos, espont\u00e1neos y optimistas<\/strong>;\u00a0<strong>los verdes, pacientes y amables<\/strong>, y\u00a0<strong>los azules, met\u00f3dicos y precisos<\/strong>. Este libro da herramientas para identificarlos e interactuar con ellos y, con un trasfondo psicol\u00f3gico y partiendo de situaciones cotidianas, nos permite mejorar nuestras habilidades sociales y afrontar los conflictos en nuestra vida profesional y personal, con el fin de sacar lo mejor de nosotros mismos y de aquellos que nos rodean.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00bfAlguna vez te sientes incomprendido? \u00bfHas intentado razonar con alguien y hab\u00e9is acabado a gritos? \u00bfHas salido de una reuni\u00f3n pensando que est\u00e1s perdiendo el tiempo? O, lo que es peor, \u00bfla gente a veces no entiende lo que dices, por m\u00e1s claramente que lo expliques? No est\u00e1s solo. Tras una reuni\u00f3n desastrosa con un [&hellip;]<\/p>\n","protected":false},"featured_media":2878,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false,"product_autor":""},"product_cat":[39],"product_tag":[],"class_list":{"0":"post-2877","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-crecimiento-personal","8":"first","9":"instock","10":"virtual","11":"purchasable","12":"product-type-simple"},"acf":[],"_links":{"self":[{"href":"https:\/\/tulibreando.com\/index.php\/wp-json\/wp\/v2\/product\/2877"}],"collection":[{"href":"https:\/\/tulibreando.com\/index.php\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/tulibreando.com\/index.php\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/tulibreando.com\/index.php\/wp-json\/wp\/v2\/comments?post=2877"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tulibreando.com\/index.php\/wp-json\/wp\/v2\/media\/2878"}],"wp:attachment":[{"href":"https:\/\/tulibreando.com\/index.php\/wp-json\/wp\/v2\/media?parent=2877"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/tulibreando.com\/index.php\/wp-json\/wp\/v2\/product_cat?post=2877"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/tulibreando.com\/index.php\/wp-json\/wp\/v2\/product_tag?post=2877"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}